﻿{"id":689,"count":58,"description":"","link":"https:\/\/www.digitalvirgo.com\/pl\/topics\/payment\/","name":"Payment","slug":"payment","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Digital Virgo &#8226; Topic Payment<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.digitalvirgo.com\/pl\/topics\/payment\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Digital Virgo &#8226; Topic Payment\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.digitalvirgo.com\/pl\/topics\/payment\/\" \/>\n<meta property=\"og:site_name\" content=\"Digital Virgo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@DigitalVirgo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.digitalvirgo.com\\\/pl\\\/topics\\\/payment\\\/\",\"url\":\"https:\\\/\\\/www.digitalvirgo.com\\\/pl\\\/topics\\\/payment\\\/\",\"name\":\"Digital Virgo &#8226; Topic Payment\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.digitalvirgo.com\\\/pl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.digitalvirgo.com\\\/pl\\\/topics\\\/payment\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.digitalvirgo.com\\\/pl\\\/topics\\\/payment\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.digitalvirgo.com\\\/pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Payment\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.digitalvirgo.com\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/www.digitalvirgo.com\\\/pl\\\/\",\"name\":\"Digital Virgo\",\"description\":\"Making the most of Mobile Payment\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.digitalvirgo.com\\\/pl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.digitalvirgo.com\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.digitalvirgo.com\\\/pl\\\/#organization\",\"name\":\"Digital Virgo\",\"url\":\"https:\\\/\\\/www.digitalvirgo.com\\\/pl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/www.digitalvirgo.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.digitalvirgo.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/DV_Square_No-Baseline-\u2013-1.png\",\"contentUrl\":\"https:\\\/\\\/www.digitalvirgo.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/DV_Square_No-Baseline-\u2013-1.png\",\"width\":360,\"height\":133,\"caption\":\"Digital Virgo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.digitalvirgo.com\\\/pl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/digitalvirgo\\\/\",\"https:\\\/\\\/x.com\\\/DigitalVirgo\",\"https:\\\/\\\/www.instagram.com\\\/digitalvirgo\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/digitalvirgo\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCWOpLAp39LC7EZPg60f8jrQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Digital Virgo &#8226; Topic Payment","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.digitalvirgo.com\/pl\/topics\/payment\/","og_locale":"pl_PL","og_type":"article","og_title":"Digital Virgo &#8226; Topic Payment","og_url":"https:\/\/www.digitalvirgo.com\/pl\/topics\/payment\/","og_site_name":"Digital Virgo","twitter_card":"summary_large_image","twitter_site":"@DigitalVirgo","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.digitalvirgo.com\/pl\/topics\/payment\/","url":"https:\/\/www.digitalvirgo.com\/pl\/topics\/payment\/","name":"Digital Virgo &#8226; Topic Payment","isPartOf":{"@id":"https:\/\/www.digitalvirgo.com\/pl\/#website"},"breadcrumb":{"@id":"https:\/\/www.digitalvirgo.com\/pl\/topics\/payment\/#breadcrumb"},"inLanguage":"pl-PL"},{"@type":"BreadcrumbList","@id":"https:\/\/www.digitalvirgo.com\/pl\/topics\/payment\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.digitalvirgo.com\/pl\/"},{"@type":"ListItem","position":2,"name":"Payment"}]},{"@type":"WebSite","@id":"https:\/\/www.digitalvirgo.com\/pl\/#website","url":"https:\/\/www.digitalvirgo.com\/pl\/","name":"Digital Virgo","description":"Making the most of Mobile Payment","publisher":{"@id":"https:\/\/www.digitalvirgo.com\/pl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.digitalvirgo.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/www.digitalvirgo.com\/pl\/#organization","name":"Digital Virgo","url":"https:\/\/www.digitalvirgo.com\/pl\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/www.digitalvirgo.com\/pl\/#\/schema\/logo\/image\/","url":"https:\/\/www.digitalvirgo.com\/wp-content\/uploads\/2020\/07\/DV_Square_No-Baseline-\u2013-1.png","contentUrl":"https:\/\/www.digitalvirgo.com\/wp-content\/uploads\/2020\/07\/DV_Square_No-Baseline-\u2013-1.png","width":360,"height":133,"caption":"Digital Virgo"},"image":{"@id":"https:\/\/www.digitalvirgo.com\/pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/digitalvirgo\/","https:\/\/x.com\/DigitalVirgo","https:\/\/www.instagram.com\/digitalvirgo\/","https:\/\/www.linkedin.com\/company\/digitalvirgo\/","https:\/\/www.youtube.com\/channel\/UCWOpLAp39LC7EZPg60f8jrQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.digitalvirgo.com\/pl\/wp-json\/wp\/v2\/tags\/689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.digitalvirgo.com\/pl\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.digitalvirgo.com\/pl\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.digitalvirgo.com\/pl\/wp-json\/wp\/v2\/posts?tags=689"},{"href":"https:\/\/www.digitalvirgo.com\/pl\/wp-json\/wp\/v2\/blog?tags=689"},{"href":"https:\/\/www.digitalvirgo.com\/pl\/wp-json\/wp\/v2\/country-cards?tags=689"},{"href":"https:\/\/www.digitalvirgo.com\/pl\/wp-json\/wp\/v2\/event?tags=689"},{"href":"https:\/\/www.digitalvirgo.com\/pl\/wp-json\/wp\/v2\/glossary?tags=689"},{"href":"https:\/\/www.digitalvirgo.com\/pl\/wp-json\/wp\/v2\/newsroom?tags=689"},{"href":"https:\/\/www.digitalvirgo.com\/pl\/wp-json\/wp\/v2\/success-case?tags=689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}